{"id":8558,"date":"2018-07-10T08:36:21","date_gmt":"2018-07-10T08:36:21","guid":{"rendered":"http:\/\/www.fiveminutesspare.com\/news\/tesco-uk-chief-steps-down-over-cancer\/business\/"},"modified":"2018-07-10T08:36:21","modified_gmt":"2018-07-10T08:36:21","slug":"tesco-uk-chief-steps-down-over-cancer","status":"publish","type":"post","link":"https:\/\/www.fiveminutesspare.com\/news\/tesco-uk-chief-steps-down-over-cancer\/","title":{"rendered":"Tesco UK chief steps down over cancer"},"content":{"rendered":"<p>Charles Wilson is stepping down from the company board after being diagnosed with throat cancer.<br \/>\n<a rel=\"nofollow\" href=\"https:\/\/www.bbc.co.uk\/news\/business-44777207\">BBC News &#8211; Business<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Charles Wilson is stepping down from the company board after being diagnosed with throat cancer. BBC News &#8211; Business<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"om_disable_all_campaigns":false,"footnotes":""},"categories":[34],"tags":[],"class_list":["post-8558","post","type-post","status-publish","format-standard","hentry","category-business"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.fiveminutesspare.com\/news\/wp-json\/wp\/v2\/posts\/8558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiveminutesspare.com\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiveminutesspare.com\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiveminutesspare.com\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiveminutesspare.com\/news\/wp-json\/wp\/v2\/comments?post=8558"}],"version-history":[{"count":0,"href":"https:\/\/www.fiveminutesspare.com\/news\/wp-json\/wp\/v2\/posts\/8558\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fiveminutesspare.com\/news\/wp-json\/wp\/v2\/media?parent=8558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiveminutesspare.com\/news\/wp-json\/wp\/v2\/categories?post=8558"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiveminutesspare.com\/news\/wp-json\/wp\/v2\/tags?post=8558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}